{"id":10306,"date":"2024-02-28T08:50:05","date_gmt":"2024-02-28T06:50:05","guid":{"rendered":"https:\/\/eoc.vision\/case-study-truck-welt\/"},"modified":"2024-11-18T10:32:00","modified_gmt":"2024-11-18T08:32:00","slug":"case-study-truck-welt","status":"publish","type":"post","link":"https:\/\/eoc.vision\/de\/case-study-truck-welt\/","title":{"rendered":"Case Study: Truck Welt"},"content":{"rendered":"<p><strong><em>\u201c<a href=\"https:\/\/eoc.vision\/de\/unternehmenskultur-und-branding\/\">Markenidentit\u00e4t<\/a> und konkrete Werte\u201d<\/em><\/strong><\/p>\n<p>Im Jahr 2015 begann unsere Zusammenarbeit mit Edi Menapace, dem Inhaber von Arca Bozen Srl, einem Ersatzteilzentrum f\u00fcr Lkw-Fahrer und der Werkstatt Edi Menapace, einer spezialisierten Werkstatt f\u00fcr Lkw und Anh\u00e4nger.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10294\" src=\"https:\/\/eoc.vision\/wp-content\/uploads\/2024\/02\/logo_truckwelt_colors_estesa-300x68.png\" alt=\"|\" width=\"988\" height=\"224\" title=\"\" srcset=\"https:\/\/eoc.vision\/wp-content\/uploads\/2024\/02\/logo_truckwelt_colors_estesa-300x68.png 300w, https:\/\/eoc.vision\/wp-content\/uploads\/2024\/02\/logo_truckwelt_colors_estesa-1024x231.png 1024w, https:\/\/eoc.vision\/wp-content\/uploads\/2024\/02\/logo_truckwelt_colors_estesa-768x173.png 768w, https:\/\/eoc.vision\/wp-content\/uploads\/2024\/02\/logo_truckwelt_colors_estesa-1536x346.png 1536w\" sizes=\"auto, (max-width: 988px) 100vw, 988px\" \/><\/p>\n<h2>Marketing<\/h2>\n<p>In diesen Jahren wurden zwei Marketingpl\u00e4ne mit j\u00e4hrlichen Anpassungen erstellt.<\/p>\n<p>Aufgrund der engen Verbindung der beiden Unternehmen, die oft durch gemeinsame Aktivit\u00e4ten vernetzt sind, bestand die Notwendigkeit, eine klare Markenidentit\u00e4t zu schaffen, die alle Aktivit\u00e4ten zusammenfasst und ihnen eine klare Ausrichtung gibt. Truck Welt wurde geboren, w\u00f6rtlich die Welt des Lastwagens.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Die starke ethische Verpflichtung des Eigent\u00fcmers wurde seitens des Marktes erschwert, welcher insbesondere in diesem Sektor s\u00e4mtliche \u00dcberlegungen, sei es im Vertrieb als auch im Service, auf Preis- und Margendynamiken aufbaut. Die Schaffung einer tiefgreifenden ethischen Identit\u00e4t schien eine von vornherein verlorene Herausforderung zu sein. Aber zum Gl\u00fcck war das nicht der Fall.<\/p>\n<ul>\n<li>Marketingplan und 2 j\u00e4hrliche \u00dcberarbeitungen<\/li>\n<li>Entwicklung der <a href=\"https:\/\/eoc.vision\/de\/leitfaden-zur-markenarchitektur\/\">Marke<\/a> Truck Welt<\/li>\n<li>Erstellung des Pay-off &#8211; Enjoy your way<\/li>\n<li data-stringify-indent=\"0\" data-stringify-border=\"0\">Schaffung der Markenidentit\u00e4t und des USP<\/li>\n<li>Mission<\/li>\n<li>Vision<\/li>\n<li>Werte und <a href=\"https:\/\/eoc.vision\/de\/rebranding-wann-und-warum\/\">Daseinszweck<\/a><\/li>\n<\/ul>\n<h2>Vertriebsentwicklung<\/h2>\n<p>Das Unternehmen hat sich durch den Aufbau einer soliden Vertriebsstruktur weiterentwickelt.<\/p>\n<p>Wir haben das Vertriebsnetz gemeinsam entwickelt, die Verkaufsaktivit\u00e4ten durch Kundenprofilierung und -segmentierung systematisiert und eine CRM-Kultur im Unternehmen eingef\u00fchrt, um das Unternehmen bei strategischen Entscheidungen zu unterst\u00fctzen.<\/p>\n<p>TRUCK WELT &#8211; VERTRIEB<\/p>\n<ul>\n<li>TEXA &#8211; Diagnose<\/li>\n<li>DRAGO &#8211; Ausstattung<\/li>\n<li>SERMAC &#8211; Betonpumpen<\/li>\n<li>MARCOLIN &#8211; Planen und Abdeckungen<\/li>\n<li>CRAMARO &#8211; Planen und Abdeckungen f\u00fcr Lkw<\/li>\n<li>MAURELLI GROUP &#8211; internationaler Gro\u00dfh\u00e4ndler f\u00fcr Aftermarket-Ersatzteile<\/li>\n<li>GLASMOP &#8211; Europ\u00e4ischer Marktf\u00fchrer f\u00fcr Glasproduktion im Baustellen- und Landwirtschaftsbereich<\/li>\n<\/ul>\n<h2>Markenidentit\u00e4t<\/h2>\n<p>Eine Marke in der Welt des Lastwagens aufzubauen war f\u00fcr uns mehr als eine Herausforderung. Es war noch schwieriger, dies f\u00fcr ein lokales Unternehmen zu tun, das wachsen und sich auch international entwickeln wollte. Wir gingen davon aus, dass der Lkw-Fahrer einerseits d\u00e4monisiert wird und andererseits jeden Tag sein Leben auf der Stra\u00dfe riskiert. Die Welt mit den Augen des Lkw-Fahrers, des Spediteurs zu sehen und sich in seine Realit\u00e4t hineinzuversetzen, war der erste Schritt, der uns klar zeigte, welchen Weg wir in jeder Hinsicht einschlagen sollten. Truck Welt &#8211; Enjoy your way m\u00f6chte das Leben dieser Menschen sch\u00fctzen, indem es konkret Materialien von h\u00f6chster und erlesener Qualit\u00e4t verkauft, st\u00e4ndige Unterst\u00fctzung, Beratung und Einsatz zur Verbesserung der Arbeit dieser Menschen bietet, die reisen, um uns und die Gemeinschaft mit notwendigen Dienstleistungen zu versorgen.<\/p>\n<h2>2023\/2024<\/h2>\n<p>Die n\u00e4chsten Schritte f\u00fcr Truck Welt stellen einen gro\u00dfen strategischen Wert dar, um die eigenen Marktanteile zu festigen. Hierein fallen die St\u00e4rkung der Markenidentit\u00e4t durch die Erstellung einer neuen Website (in Ausarbeitung) und eine Reihe wichtiger Performance-Marketingaktivit\u00e4ten zur Unterst\u00fctzung der Kommunikation der Vertriebsentwicklung des Unternehmens.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cMarkenidentit\u00e4t und konkrete Werte\u201d Im Jahr 2015 begann unsere Zusammenarbeit mit Edi Menapace, dem Inhaber von Arca Bozen Srl, einem Ersatzteilzentrum f\u00fcr Lkw-Fahrer und der Werkstatt Edi Menapace, einer spezialisierten Werkstatt f\u00fcr Lkw und Anh\u00e4nger. Marketing In diesen Jahren wurden zwei Marketingpl\u00e4ne&#8230;<\/p>\n","protected":false},"author":5,"featured_media":10283,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[179],"tags":[],"class_list":{"0":"post-10306","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-case-study-de"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/posts\/10306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/comments?post=10306"}],"version-history":[{"count":0,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/posts\/10306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/media\/10283"}],"wp:attachment":[{"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/media?parent=10306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/categories?post=10306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eoc.vision\/de\/wp-json\/wp\/v2\/tags?post=10306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}